{"id":90,"date":"2023-08-10T08:31:56","date_gmt":"2023-08-10T08:31:56","guid":{"rendered":"https:\/\/www.cotefleurs.ch\/?post_type=product&#038;p=90"},"modified":"2023-10-24T07:38:17","modified_gmt":"2023-10-24T07:38:17","slug":"panier-fleuri-pastel","status":"publish","type":"product","link":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/","title":{"rendered":"Panier fleuri pastel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2279,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[40,35],"product_tag":[],"class_list":["post-90","product","type-product","status-publish","has-post-thumbnail","product_cat-coussins","product_cat-dernier-hommage","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coussins de fleurs Pastel pour enterrement \u00e0 Gen\u00e8ve<\/title>\n<meta name=\"description\" content=\"Rendez un hommage d\u00e9licat avec nos Coussins Pastel. Votre fleuriste en ligne pour une livraison attentive \u00e0 Gen\u00e8ve.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coussins de fleurs Pastel pour enterrement \u00e0 Gen\u00e8ve\" \/>\n<meta property=\"og:description\" content=\"Rendez un hommage d\u00e9licat avec nos Coussins Pastel. Votre fleuriste en ligne pour une livraison attentive \u00e0 Gen\u00e8ve.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4t\u00e9 fleurs\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T07:38:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cotefleurs.ch\/wp-content\/uploads\/2023\/08\/65-Coussin-pastel-350-CHF-copie.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/\",\"url\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/\",\"name\":\"Coussins de fleurs Pastel pour enterrement \u00e0 Gen\u00e8ve\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cotefleurs.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/65-Coussin-pastel-350-CHF-copie.webp\",\"datePublished\":\"2023-08-10T08:31:56+00:00\",\"dateModified\":\"2023-10-24T07:38:17+00:00\",\"description\":\"Rendez un hommage d\u00e9licat avec nos Coussins Pastel. Votre fleuriste en ligne pour une livraison attentive \u00e0 Gen\u00e8ve.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cotefleurs.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/65-Coussin-pastel-350-CHF-copie.webp\",\"contentUrl\":\"https:\\\/\\\/www.cotefleurs.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/65-Coussin-pastel-350-CHF-copie.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Coussin pastel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/acheter-en-ligne\\\/dernier-hommage\\\/arrangements-et-coussins\\\/pastel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cotefleurs.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Panier fleuri pastel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/\",\"name\":\"C\u00f4t\u00e9 fleurs\",\"description\":\"Fleuriste \u00e0 Gen\u00e8ve\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/#organization\",\"name\":\"C\u00f4t\u00e9 fleurs\",\"url\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cotefleurs.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-cote-fleurs-fleuriste-geneve-livraison-fleurs.webp\",\"contentUrl\":\"https:\\\/\\\/www.cotefleurs.ch\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-cote-fleurs-fleuriste-geneve-livraison-fleurs.webp\",\"width\":400,\"height\":400,\"caption\":\"C\u00f4t\u00e9 fleurs\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cotefleurs.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coussins de fleurs Pastel pour enterrement \u00e0 Gen\u00e8ve","description":"Rendez un hommage d\u00e9licat avec nos Coussins Pastel. Votre fleuriste en ligne pour une livraison attentive \u00e0 Gen\u00e8ve.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/","og_locale":"fr_FR","og_type":"article","og_title":"Coussins de fleurs Pastel pour enterrement \u00e0 Gen\u00e8ve","og_description":"Rendez un hommage d\u00e9licat avec nos Coussins Pastel. Votre fleuriste en ligne pour une livraison attentive \u00e0 Gen\u00e8ve.","og_url":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/","og_site_name":"C\u00f4t\u00e9 fleurs","article_modified_time":"2023-10-24T07:38:17+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.cotefleurs.ch\/wp-content\/uploads\/2023\/08\/65-Coussin-pastel-350-CHF-copie.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/","url":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/","name":"Coussins de fleurs Pastel pour enterrement \u00e0 Gen\u00e8ve","isPartOf":{"@id":"https:\/\/www.cotefleurs.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/#primaryimage"},"image":{"@id":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cotefleurs.ch\/wp-content\/uploads\/2023\/08\/65-Coussin-pastel-350-CHF-copie.webp","datePublished":"2023-08-10T08:31:56+00:00","dateModified":"2023-10-24T07:38:17+00:00","description":"Rendez un hommage d\u00e9licat avec nos Coussins Pastel. Votre fleuriste en ligne pour une livraison attentive \u00e0 Gen\u00e8ve.","breadcrumb":{"@id":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/#primaryimage","url":"https:\/\/www.cotefleurs.ch\/wp-content\/uploads\/2023\/08\/65-Coussin-pastel-350-CHF-copie.webp","contentUrl":"https:\/\/www.cotefleurs.ch\/wp-content\/uploads\/2023\/08\/65-Coussin-pastel-350-CHF-copie.webp","width":1000,"height":1000,"caption":"Coussin pastel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cotefleurs.ch\/fr\/acheter-en-ligne\/dernier-hommage\/arrangements-et-coussins\/pastel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cotefleurs.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.cotefleurs.ch\/fr\/shop\/"},{"@type":"ListItem","position":3,"name":"Panier fleuri pastel"}]},{"@type":"WebSite","@id":"https:\/\/www.cotefleurs.ch\/fr\/#website","url":"https:\/\/www.cotefleurs.ch\/fr\/","name":"C\u00f4t\u00e9 fleurs","description":"Fleuriste \u00e0 Gen\u00e8ve","publisher":{"@id":"https:\/\/www.cotefleurs.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cotefleurs.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cotefleurs.ch\/fr\/#organization","name":"C\u00f4t\u00e9 fleurs","url":"https:\/\/www.cotefleurs.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cotefleurs.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cotefleurs.ch\/wp-content\/uploads\/2023\/08\/logo-cote-fleurs-fleuriste-geneve-livraison-fleurs.webp","contentUrl":"https:\/\/www.cotefleurs.ch\/wp-content\/uploads\/2023\/08\/logo-cote-fleurs-fleuriste-geneve-livraison-fleurs.webp","width":400,"height":400,"caption":"C\u00f4t\u00e9 fleurs"},"image":{"@id":"https:\/\/www.cotefleurs.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/product\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":5,"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/product\/90\/revisions"}],"predecessor-version":[{"id":3407,"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/product\/90\/revisions\/3407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/media\/2279"}],"wp:attachment":[{"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/media?parent=90"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=90"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=90"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cotefleurs.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}